{"id":775,"date":"2005-11-08T13:31:09","date_gmt":"2005-11-08T10:49:09","guid":{"rendered":"http:\/\/s656050976.online.de\/gamersliving\/wowblog\/2005\/11\/08\/voice-clients-endlicha-uch-fuer-den-mac\/"},"modified":"2005-11-08T13:31:36","modified_gmt":"2005-11-08T10:49:36","slug":"voice-clients-endlicha-uch-fuer-den-mac","status":"publish","type":"post","link":"http:\/\/www.gamersliving.com\/wowblog\/2005\/11\/08\/voice-clients-endlicha-uch-fuer-den-mac\/","title":{"rendered":"Voice-Clients endlich auch f\u00c3\u00bcr den Mac!"},"content":{"rendered":"<p>Nachdem wir ja <a href=\"http:\/\/www.gamersliving.com\/wowblog\/2005\/10\/17\/teamspeak-fuer-den-mac\/\">vor einiger Zeit<\/a> bereits \u00c3\u00bcber <a href=\"http:\/\/www.savvy.nl\/blog\/\">TeamSpeex<\/a> &#8211; den TeamSpeak Client f\u00c3\u00bcr den Mac &#8211; berichtet haben folgt nun die n\u00c3\u00a4chste gute Botschaft: Ventrilo ist nun ebenfalls <a href=\"http:\/\/www.ventrilo.com\/news.php?article=mac-232prototype6\">in einer Mac-Version erh\u00c3\u00a4ltlich<\/a>.<\/p>\n<p>Damit gibts es nun keine Ausreden mehr f\u00c3\u00bcr Abwesenheit auf einem Voice\/Speech-Server&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem wir ja vor einiger Zeit bereits \u00c3\u00bcber TeamSpeex &#8211; den TeamSpeak Client f\u00c3\u00bcr den Mac &#8211; berichtet haben folgt nun die n\u00c3\u00a4chste gute Botschaft: Ventrilo ist nun ebenfalls in einer Mac-Version erh\u00c3\u00a4ltlich. Damit gibts es nun keine Ausreden mehr f\u00c3\u00bcr Abwesenheit auf einem Voice\/Speech-Server&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[85,125],"class_list":["post-775","post","type-post","status-publish","format-standard","hentry","category-news","tag-teamspeak","tag-ventrilo"],"_links":{"self":[{"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/posts\/775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/comments?post=775"}],"version-history":[{"count":0,"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/posts\/775\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/media?parent=775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/categories?post=775"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.gamersliving.com\/wowblog\/wp-json\/wp\/v2\/tags?post=775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}